{"id":9006,"date":"2026-05-12T10:31:49","date_gmt":"2026-05-12T10:31:49","guid":{"rendered":"https:\/\/westatix.com\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/"},"modified":"2026-05-12T10:49:50","modified_gmt":"2026-05-12T10:49:50","slug":"gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi","status":"publish","type":"post","link":"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/","title":{"rendered":"Gemello digitale e monitoraggio avanzato per la sicurezza del Viadotto dei Parchi"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]L&#8217;invecchiamento delle infrastrutture autostradali sta diventando una delle maggiori sfide per i gestori dei trasporti in tutta Europa. L&#8217;aumento dei volumi di traffico, il degrado dei materiali e i requisiti di sicurezza pi\u00f9 stringenti spingono i gestori delle infrastrutture ad adottare soluzioni di monitoraggio pi\u00f9 intelligenti e affidabili. <\/p>\n<p>\u00c8 proprio in questo contesto che CAEmate e Milano Serravalle \u2013 Milano Tangenziali hanno collaborato a un progetto avanzato di Monitoraggio Strutturale (SHM) incentrato su una delle infrastrutture pi\u00f9 strategiche di Milano: il <em>Viadotto dei Parchi<\/em> .[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Il progetto&#8221; font_size=&#8221;1.7vw&#8221; font_line_height=&#8221;1.7&#8243;][\/split_line_heading][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Il progetto fu guidato da Giuseppe Colombo, all&#8217;epoca Direttore Tecnico, responsabile della supervisione tecnica delle infrastrutture in concessione, tra cui l&#8217;autostrada A7 Milano-Genova e la tangenziale di Milano.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_video link=&#8221;https:\/\/youtu.be\/bqINmMnXrx0&#8243; align=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3 data-section-id=\"1y9urfn\" data-start=\"635\" data-end=\"677\">La sfida del monitoraggio del viadotto di Parchi<\/h3>\n<p>Il <em>Viadotto dei Parchi<\/em> , situato sulla tangenziale est di Milano, \u00e8 una delle infrastrutture pi\u00f9 importanti della rete autostradale Milano-Serravalle.<\/p>\n<p>Originariamente progettato negli anni &#8217;70 dall&#8217;ingegnere Silvano Zorzi, il viadotto \u00e8 una struttura in cemento precompresso lunga quasi 3 chilometri, composta da due carreggiate parallele. Negli anni &#8217;90, l&#8217;impalcato \u00e8 stato ampliato per far fronte all&#8217;aumento dei volumi di traffico, il che ha comportato un&#8217;ulteriore complessit\u00e0 strutturale. <\/p>\n<p>Come molte strutture autostradali storiche, il viadotto \u00e8 esposto a:<\/p>\n<ul>\n<li>invecchiamento del calcestruzzo,<\/li>\n<li>degrado ambientale,<\/li>\n<li>aumento dei carichi di traffico,<\/li>\n<li>e condizioni di ispezione difficili.<\/li>\n<\/ul>\n<p>I metodi di ispezione tradizionali fornivano solo valutazioni periodiche e qualitative, rendendo difficile valutare in modo continuo il reale comportamento strutturale e i margini di sicurezza delle infrastrutture.<\/p>\n<p>Per Milano Serravalle, ci\u00f2 ha creato la necessit\u00e0 di un approccio di monitoraggio pi\u00f9 avanzato e basato sui dati.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;8993&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Perch\u00e9 Milano Serravalle ha scelto CAEmate&#8221; font_size=&#8221;1.7vw&#8221; font_line_height=&#8221;1.7&#8243;][\/split_line_heading][vc_column_text]Nel 2023, Milano Serravalle ha lanciato un&#8217;iniziativa di monitoraggio delle infrastrutture supportata da finanziamenti europei e ha avviato una collaborazione con CAEmate.<\/p>\n<p>L&#8217;obiettivo non era semplicemente raccogliere dati dai sensori, ma creare un sistema intelligente in grado di interpretare il comportamento strutturale in tempo reale.<\/p>\n<p>Una delle principali difficolt\u00e0 era rappresentata dalla disponibilit\u00e0 incompleta della documentazione originale relativa alla costruzione e dalla potenziale presenza di imperfezioni strutturali nascoste accumulate nel corso di decenni di attivit\u00e0.<\/p>\n<p>L&#8217;approccio di CAEmate si \u00e8 distinto perch\u00e9 combina:<\/p>\n<ul>\n<li>Ingegneria inversa basata sull&#8217;intelligenza artificiale,<\/li>\n<li>tecnologia del gemello digitale,<\/li>\n<li>monitoraggio in tempo reale,<\/li>\n<li>e analisi strutturale predittiva.<\/li>\n<\/ul>\n<p>Ci\u00f2 ha permesso di generare una rappresentazione digitale estremamente accurata dell&#8217;infrastruttura, in grado di aggiornarsi continuamente utilizzando dati di monitoraggio reali.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Implementazione di WeStatiX SHM&#8221; font_size=&#8221;1.7vw&#8221; font_line_height=&#8221;1.7&#8243;][\/split_line_heading][vc_column_text]Per supportare questa trasformazione, Milano Serravalle ha implementato WeStatiX SHM di CAEmate sulle sue infrastrutture pi\u00f9 critiche.<\/p>\n<p>Il sistema di monitoraggio strutturale comprende:<\/p>\n<ul>\n<li>sensori a fibra ottica,<\/li>\n<li>accelerometri,<\/li>\n<li>inclinometri,<\/li>\n<li>e acquisizione continua di dati strutturali statici e dinamici.<\/li>\n<\/ul>\n<p>La piattaforma \u00e8 stata installata su circa 340 campate all&#8217;interno della rete autostradale e confronta continuamente il comportamento strutturale reale con le previsioni generate dal gemello digitale.<\/p>\n<p>Ci\u00f2 consente agli ingegneri di:<\/p>\n<ul>\n<li>monitorare le condizioni dell&#8217;infrastruttura in tempo reale,<\/li>\n<li>migliorare le valutazioni della sicurezza strutturale,<\/li>\n<li>ridurre l&#8217;incertezza nelle decisioni di manutenzione,<\/li>\n<li>e ottimizzare le attivit\u00e0 di ispezione.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Dalle ispezioni periodiche alla gestione predittiva delle infrastrutture&#8221; font_size=&#8221;1.7vw&#8221; font_line_height=&#8221;1.7&#8243;][\/split_line_heading][vc_column_text]L&#8217;implementazione della piattaforma SHM ha trasformato il flusso di lavoro ingegneristico, passando da valutazioni periodiche basate su ispezioni a un monitoraggio strutturale continuo.<\/p>\n<p>Secondo Giuseppe Colombo, Direttore Tecnico di Milano Serravalle \u2013 Milano Tangenziali, il sistema fornisce una comprensione molto pi\u00f9 chiara di come le strutture rispondono ai carichi operativi nel tempo.<\/p>\n<p>La piattaforma di monitoraggio migliora anche:<\/p>\n<ul>\n<li>velocit\u00e0 decisionale,<\/li>\n<li>obiettivit\u00e0 nella valutazione dei difetti,<\/li>\n<li>e l&#8217;efficienza della pianificazione della manutenzione.<\/li>\n<\/ul>\n<p>Inoltre, il monitoraggio remoto consente di ridurre la frequenza delle ispezioni visive, generando notevoli vantaggi operativi ed economici.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;8997&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Validazione del gemello digitale del viadotto Parchi&#8221; font_size=&#8221;1.7vw&#8221; font_line_height=&#8221;1.7&#8243;][\/split_line_heading][vc_column_text]Per convalidare l&#8217;affidabilit\u00e0 del gemello digitale, diverse campate del <em>Viadotto dei Parchi<\/em> sono state sottoposte a prove di carico statico utilizzando sei autocarri a pieno carico del peso di circa 30-32 tonnellate ciascuno.<\/p>\n<p> Le stesse condizioni di carico sono state simulate all&#8217;interno dell&#8217;ambiente del gemello digitale utilizzando modelli dettagliati di distribuzione strutturale e dei carichi.<\/p>\n<p> Il confronto tra gli spostamenti misurati e quelli simulati ha mostrato discrepanze inferiori al 5%, confermando l&#8217;elevata accuratezza del modello e la sua capacit\u00e0 di riprodurre il comportamento reale della struttura.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Un nuovo approccio al monitoraggio dello stato di salute delle strutture.&#8221; font_size=&#8221;1.7vw&#8221; font_line_height=&#8221;1.7&#8243;][\/split_line_heading][vc_column_text]L&#8217;esperienza di Milano Serravalle dimostra come la tecnologia del digital twin e i sistemi avanzati di monitoraggio strutturale possano supportare una gestione delle infrastrutture pi\u00f9 sicura, efficiente e predittiva.<\/p>\n<p>Integrando i dati dei sensori in tempo reale con modelli strutturali basati sull&#8217;intelligenza artificiale, gli operatori possono:<\/p>\n<ul>\n<li>migliorare la sicurezza delle infrastrutture,<\/li>\n<li>ottimizzare i costi di manutenzione,<\/li>\n<li>ridurre l&#8217;incertezza operativa,<\/li>\n<li>e prolungare il ciclo di vita delle risorse critiche.<\/li>\n<\/ul>\n<p>Con l&#8217;invecchiamento delle infrastrutture di trasporto, soluzioni come WeStatiX SHM di CAEmate stanno diventando strumenti essenziali per il futuro del monitoraggio di ponti e viadotti.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;9000&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":8994,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,86,76,88],"tags":[74,66,64,68,70],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gemello digitale e monitoraggio avanzato per la sicurezza del Viadotto dei Parchi - WeStatiX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemello digitale e monitoraggio avanzato per la sicurezza del Viadotto dei Parchi - WeStatiX\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/\" \/>\n<meta property=\"og:site_name\" content=\"WeStatiX\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T10:31:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:49:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/westatix.com\/wp-content\/uploads\/2026\/05\/la-manutenzione-dei-giunti-del-viadotto-dei-parchi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cmmanuela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cmmanuela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/\",\"url\":\"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/\",\"name\":\"Gemello digitale e monitoraggio avanzato per la sicurezza del Viadotto dei Parchi - WeStatiX\",\"isPartOf\":{\"@id\":\"https:\/\/westatix.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/westatix.com\/wp-content\/uploads\/2026\/05\/la-manutenzione-dei-giunti-del-viadotto-dei-parchi.png\",\"datePublished\":\"2026-05-12T10:31:49+00:00\",\"dateModified\":\"2026-05-12T10:49:50+00:00\",\"author\":{\"@id\":\"https:\/\/westatix.com\/it\/#\/schema\/person\/f7b6af2f8bbdc0cad735a4c0678ca757\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/#primaryimage\",\"url\":\"https:\/\/westatix.com\/wp-content\/uploads\/2026\/05\/la-manutenzione-dei-giunti-del-viadotto-dei-parchi.png\",\"contentUrl\":\"https:\/\/westatix.com\/wp-content\/uploads\/2026\/05\/la-manutenzione-dei-giunti-del-viadotto-dei-parchi.png\",\"width\":730,\"height\":504},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/westatix.com\/it\/#website\",\"url\":\"https:\/\/westatix.com\/it\/\",\"name\":\"WeStatiX\",\"description\":\"Structural Health Monitoring\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/westatix.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/westatix.com\/it\/#\/schema\/person\/f7b6af2f8bbdc0cad735a4c0678ca757\",\"name\":\"cmmanuela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/westatix.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8ac7d03066aec7307c46500407c37bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8ac7d03066aec7307c46500407c37bc?s=96&d=mm&r=g\",\"caption\":\"cmmanuela\"},\"url\":\"https:\/\/westatix.com\/it\/author\/cmmanuela\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemello digitale e monitoraggio avanzato per la sicurezza del Viadotto dei Parchi - WeStatiX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/","og_locale":"it_IT","og_type":"article","og_title":"Gemello digitale e monitoraggio avanzato per la sicurezza del Viadotto dei Parchi - WeStatiX","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;...","og_url":"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/","og_site_name":"WeStatiX","article_published_time":"2026-05-12T10:31:49+00:00","article_modified_time":"2026-05-12T10:49:50+00:00","og_image":[{"width":730,"height":504,"url":"https:\/\/westatix.com\/wp-content\/uploads\/2026\/05\/la-manutenzione-dei-giunti-del-viadotto-dei-parchi.png","type":"image\/png"}],"author":"cmmanuela","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"cmmanuela","Tempo di lettura stimato":"16 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/","url":"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/","name":"Gemello digitale e monitoraggio avanzato per la sicurezza del Viadotto dei Parchi - WeStatiX","isPartOf":{"@id":"https:\/\/westatix.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/#primaryimage"},"image":{"@id":"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/#primaryimage"},"thumbnailUrl":"https:\/\/westatix.com\/wp-content\/uploads\/2026\/05\/la-manutenzione-dei-giunti-del-viadotto-dei-parchi.png","datePublished":"2026-05-12T10:31:49+00:00","dateModified":"2026-05-12T10:49:50+00:00","author":{"@id":"https:\/\/westatix.com\/it\/#\/schema\/person\/f7b6af2f8bbdc0cad735a4c0678ca757"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/westatix.com\/it\/gemello-digitale-e-monitoraggio-avanzato-per-la-sicurezza-del-viadotto-dei-parchi\/#primaryimage","url":"https:\/\/westatix.com\/wp-content\/uploads\/2026\/05\/la-manutenzione-dei-giunti-del-viadotto-dei-parchi.png","contentUrl":"https:\/\/westatix.com\/wp-content\/uploads\/2026\/05\/la-manutenzione-dei-giunti-del-viadotto-dei-parchi.png","width":730,"height":504},{"@type":"WebSite","@id":"https:\/\/westatix.com\/it\/#website","url":"https:\/\/westatix.com\/it\/","name":"WeStatiX","description":"Structural Health Monitoring","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/westatix.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/westatix.com\/it\/#\/schema\/person\/f7b6af2f8bbdc0cad735a4c0678ca757","name":"cmmanuela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/westatix.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8ac7d03066aec7307c46500407c37bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8ac7d03066aec7307c46500407c37bc?s=96&d=mm&r=g","caption":"cmmanuela"},"url":"https:\/\/westatix.com\/it\/author\/cmmanuela\/"}]}},"_links":{"self":[{"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/posts\/9006"}],"collection":[{"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/comments?post=9006"}],"version-history":[{"count":12,"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/posts\/9006\/revisions"}],"predecessor-version":[{"id":9019,"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/posts\/9006\/revisions\/9019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/media\/8994"}],"wp:attachment":[{"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/media?parent=9006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/categories?post=9006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/westatix.com\/it\/wp-json\/wp\/v2\/tags?post=9006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}